{"id":195,"date":"2022-02-17T18:10:16","date_gmt":"2022-02-17T18:10:16","guid":{"rendered":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/"},"modified":"2022-02-17T18:10:16","modified_gmt":"2022-02-17T18:10:16","slug":"cart","status":"publish","type":"page","link":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-195","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart - Design Nineteen Color One<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Design Nineteen Color One\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"Design Nineteen Color One\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/cart\\\/\",\"url\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/cart\\\/\",\"name\":\"Cart - Design Nineteen Color One\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/#website\"},\"datePublished\":\"2022-02-17T18:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/cart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/cart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/cart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/#website\",\"url\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/\",\"name\":\"Design Nineteen Color One\",\"description\":\"Just another Music Teacher Websites Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musicteacherwebsites.com\\\/design-19-color-1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Design Nineteen Color One","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/","og_locale":"en_US","og_type":"article","og_title":"Cart - Design Nineteen Color One","og_url":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/","og_site_name":"Design Nineteen Color One","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/","url":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/","name":"Cart - Design Nineteen Color One","isPartOf":{"@id":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/#website"},"datePublished":"2022-02-17T18:10:16+00:00","breadcrumb":{"@id":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/#website","url":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/","name":"Design Nineteen Color One","description":"Just another Music Teacher Websites Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/pages\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":0,"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/pages\/195\/revisions"}],"wp:attachment":[{"href":"https:\/\/musicteacherwebsites.com\/design-19-color-1\/wp-json\/wp\/v2\/media?parent=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}